{"id":16094,"date":"2017-05-02T09:30:08","date_gmt":"2017-05-02T06:30:08","guid":{"rendered":"http:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13.jpg"},"modified":"2017-05-02T09:30:34","modified_gmt":"2017-05-02T06:30:34","slug":"carlex-design-mercedes-benz-sprinter-13","status":"inherit","type":"attachment","link":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/carlex-design-mercedes-benz-sprinteri-yeniden-tasarladi\/carlex-design-mercedes-benz-sprinter-13\/","title":{"rendered":"Carlex-Design-Mercedes-Benz-Sprinter-13"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13.jpg'><img width=\"300\" height=\"200\" src=\"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-300x200.jpg 300w, https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-768x512.jpg 768w, https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-1024x683.jpg 1024w, https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Carlex Design, Mercedes Sprinter\u2019\u0131 yeniden tasarlad\u0131<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1067,"file":"Carlex-Design-Mercedes-Benz-Sprinter-13.jpg","sizes":{"thumbnail":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-150x150.jpg"},"medium":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-300x200.jpg"},"medium_large":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-768x512.jpg"},"large":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-1024x683.jpg"},"feat_slider":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-628x290.jpg","width":628,"height":290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-628x290.jpg"},"post-page":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-350x175.jpg","width":350,"height":175,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-350x175.jpg"},"cat-page":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-400x200.jpg","width":400,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-400x200.jpg"},"single-page":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-900x450.jpg","width":900,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-900x450.jpg"},"post-thumbnail":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13-350x175.jpg","width":350,"height":175,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13-350x175.jpg"},"full":{"file":"Carlex-Design-Mercedes-Benz-Sprinter-13.jpg","width":1600,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":16081,"source_url":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-content\/uploads\/Carlex-Design-Mercedes-Benz-Sprinter-13.jpg","_links":{"self":[{"href":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-json\/wp\/v2\/media\/16094"}],"collection":[{"href":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitalcarmagazine.com.tr\/Web\/wp-json\/wp\/v2\/comments?post=16094"}]}}